{"id":11463,"date":"2018-07-04T08:46:37","date_gmt":"2018-07-04T11:46:37","guid":{"rendered":"https:\/\/www.vendedorautonomo.com.br\/site\/?p=11463"},"modified":"2018-07-04T08:46:37","modified_gmt":"2018-07-04T11:46:37","slug":"5-licoes-da-copa-do-mundo-para-voce-melhorar-seu-negocio-e-encantar-o-cliente","status":"publish","type":"post","link":"https:\/\/vendedorautonomo.com.br\/site\/5-licoes-da-copa-do-mundo-para-voce-melhorar-seu-negocio-e-encantar-o-cliente\/","title":{"rendered":"5 li\u00e7\u00f5es da copa do mundo para voc\u00ea melhorar seu neg\u00f3cio e encantar o cliente"},"content":{"rendered":"<p>Se inspire no maior evento esportivo do mundo e deixe seu neg\u00f3cio mais amig\u00e1vel para o p\u00fablico<br \/>\n<figure id=\"attachment_11464\" aria-describedby=\"caption-attachment-11464\" style=\"width: 940px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-full wp-image-11464\" src=\"https:\/\/www.vendedorautonomo.com.br\/site\/wp-content\/uploads\/2018\/07\/nigeria.jpg\" alt=\"\" width=\"940\" height=\"523\" \/><figcaption id=\"caption-attachment-11464\" class=\"wp-caption-text\">Nig\u00e9ria: O uniforme diferenciado, desenhado pela Nike a pedido do pa\u00eds, logo caiu no gosto dos f\u00e3s do futebol (Foto: Divulga\u00e7\u00e3o )<\/figcaption><\/figure><br \/>\nQuase metade de popula\u00e7\u00e3o mundial estar\u00e1 atenta aos jogos da\u00a0<strong>Copa do Mundo<\/strong>\u00a0at\u00e9 14 de junho, dia da grande final. A estimativa \u00e9 que a audi\u00eancia das transmiss\u00f5es das partidas entre os 32 pa\u00edses classificados para o campeonato atinja 3,4 bilh\u00f5es de pessoas.\u00a0 \u00c9 poss\u00edvel tirar algumas li\u00e7\u00f5es de marketing de venda direta ao consumidor (direct-to-consumer, em ingl\u00eas) de um evento que movimenta tanta paix\u00e3o, um ingrediente fundamental tamb\u00e9m para ligar clientes e marcas? Claro que sim. O empreendedor Zubin Mowlavi listou para a\u00a0<a href=\"https:\/\/www.entrepreneur.com\/article\/315382\" target=\"_blank\" rel=\"noopener\"><strong>Entrepreneur<\/strong><\/a>\u00a0cinco exemplos de a\u00e7\u00f5es bem-sucedidas de equipes de futebol que podem inspirar iniciativas de relacionamento direto com clientes no mundo dos neg\u00f3cios.<br \/>\n<strong>1 &#8211; Crie f\u00e3s para a sua marca<\/strong><br \/>\nA Nig\u00e9ria ganhou destaque na Copa antes mesmo de pisar nos gramados. O uniforme diferenciado, desenhado pela Nike a pedido do pa\u00eds, logo caiu no gosto dos f\u00e3s do futebol. A empresa diz que recebeu mais de 3 milh\u00f5es de pedidos da camisa nigeriana. Ou seja, uma camiseta diferenciada e atraente levou pessoas que nunca foram aficionadas pelo pa\u00eds africano a comprar e usar o uniforme do time. Conclus\u00e3o: vale apostar em solu\u00e7\u00f5es para criar uma conex\u00e3o entre os clientes e produtos. E, sim, design \u00e9 uma arma essencial de atra\u00e7\u00e3o.<br \/>\n<strong>2 &#8211; Escolha o time que vai a campo<\/strong><br \/>\nAs sele\u00e7\u00f5es que disputam a Copa do Mundo, assim como os times que competem nos campeonatos regionais, nacionais ou locais, procuram tirar o m\u00e1ximo dos times. Em alguns casos, a for\u00e7a reside em um excelente jogador. Outras contam com o poder do grupo de 11 profissionais.\u00a0 Com as empresas n\u00e3o \u00e9 diferente. \u00c9 poss\u00edvel ter um carro-chefe ou uma composi\u00e7\u00e3o de produtos em que nenhum tenha relevo, mas que no todo funcionam muito bem. Teste os produtos no mercado at\u00e9 encontrar aquele ou aqueles com maior capacidade de atrair mais consumidores e mant\u00ea-los fi\u00e9is a sua marca.<br \/>\n<strong>3 &#8211; Siga o cliente, n\u00e3o o contr\u00e1rio<\/strong><br \/>\nAssim como as equipes de futebol jogam com diferentes forma\u00e7\u00f5es em campo para explorar seus pontos fortes, as empresas devem elaborar estrat\u00e9gias de marketing e vendas de maneira que acompanhem o caminho percorrido pelos clientes e nunca imaginar que eles seguir\u00e3o o funil de marketing e publicidade estabelecido. Imagine que os consumidores est\u00e3o no campo, e que voc\u00ea ter\u00e1 de jogar com eles, indo de um lado para o outro, para frente e para tr\u00e1s, at\u00e9 que cheguem ao momento da compra.<br \/>\n<strong>4 &#8211; Espere antes de mudar de t\u00e1tica<\/strong><br \/>\nOs t\u00e9cnicos de futebol n\u00e3o mudam de t\u00e1tica de jogo o tempo todo. Em uma partida, eles esperam normalmente at\u00e9 os primeiros minutos do segundo tempo para sentir que a estrat\u00e9gia n\u00e3o funcionou e fazer as altera\u00e7\u00f5es. Nas empresas tamb\u00e9m \u00e9 preciso dar um tempo para coletar dados estat\u00edsticos suficientes para uma avalia\u00e7\u00e3o criteriosa antes de efetuar mudan\u00e7as.<br \/>\n<strong>5 &#8211; Alinhe toda a empresa<\/strong><br \/>\nNo futebol, titulares, reservas, comiss\u00e3o t\u00e9cnica e profissionais de apoio est\u00e3o igualmente empenhados em fazer o time chegar \u00e0 vit\u00f3ria, executando cada um a sua fun\u00e7\u00e3o. Nas empresas, a uni\u00e3o de esfor\u00e7os deve ser a mesma. Uma marca s\u00f3 \u00e9 vitoriosa quando cada colaborador entende os objetivos globais tra\u00e7ados pela dire\u00e7\u00e3o e sabe exatamente qual \u00e9 seu papel para atingi-los.<br \/>\n&nbsp;<br \/>\nFonte: <a href=\"https:\/\/revistapegn.globo.com\/Administracao-de-empresas\/noticia\/2018\/06\/5-licoes-da-copa-do-mundo-para-voce-melhorar-seu-negocio-e-encantar-o-cliente.html\">Pequenas Empresas &amp; Grandes Neg\u00f3cios<\/a><br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se inspire no maior evento esportivo do mundo e deixe seu neg\u00f3cio mais amig\u00e1vel para o p\u00fablico Quase metade de popula\u00e7\u00e3o mundial estar\u00e1 atenta aos jogos da\u00a0Copa do Mundo\u00a0at\u00e9 14 de junho, dia da grande final. A estimativa \u00e9 que a audi\u00eancia das transmiss\u00f5es das partidas entre os 32 pa\u00edses classificados para o campeonato atinja &hellip; <br \/><a href=\"https:\/\/vendedorautonomo.com.br\/site\/5-licoes-da-copa-do-mundo-para-voce-melhorar-seu-negocio-e-encantar-o-cliente\/\" class=\"more-link\">Continue lendo <span class=\"screen-reader-text\">5 li\u00e7\u00f5es da copa do mundo para voc\u00ea melhorar seu neg\u00f3cio e encantar o cliente<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":11464,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,117],"tags":[323,340],"class_list":["post-11463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas","category-marketing","tag-clientes","tag-copa-do-mundo"],"_links":{"self":[{"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/posts\/11463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/comments?post=11463"}],"version-history":[{"count":0,"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/posts\/11463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/media?parent=11463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/categories?post=11463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/tags?post=11463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}