{"id":10909,"date":"2017-08-31T15:49:57","date_gmt":"2017-08-31T18:49:57","guid":{"rendered":"http:\/\/www.vendedorautonomo.com.br\/site\/?p=10909"},"modified":"2018-08-20T16:57:03","modified_gmt":"2018-08-20T19:57:03","slug":"5-livros-e-ferramentas-para-colocar-o-cliente-em-primeiro-lugar","status":"publish","type":"post","link":"https:\/\/vendedorautonomo.com.br\/site\/5-livros-e-ferramentas-para-colocar-o-cliente-em-primeiro-lugar\/","title":{"rendered":"5 livros e ferramentas para colocar o cliente em primeiro lugar"},"content":{"rendered":"<p>Caio sempre foi \u00f3timo em fazer novos amigos. Ele parece ser proativo, sol\u00edcito e confi\u00e1vel. O tipo de pessoa que, depois de um almo\u00e7o, voc\u00ea sente como se j\u00e1 conhecesse h\u00e1 anos. O problema \u00e9 que, logo depois de voc\u00eas ficarem amigos, ele some. Deixa para responder o WhatsApp dois dias depois, n\u00e3o atende as liga\u00e7\u00f5es e, no fundo, n\u00e3o est\u00e1 muito preocupado em saber como voc\u00ea est\u00e1. Ele \u00e9 aquela pessoa que est\u00e1 sempre rodeada de gente diferente, mudando de amigos como troca de roupa.<br \/>\nAlguns empreendedores s\u00e3o exatamente como Caio. Treinam um time inteiro de Vendas para ter o pitch na ponta da l\u00edngua e convencer os novos clientes de que s\u00e3o proativos, sol\u00edcitos e confi\u00e1veis. Por\u00e9m, depois de fechado o neg\u00f3cio, desaparecem do radar. O SAC n\u00e3o responde, o 0800 deixa o cliente esperando, o atendente n\u00e3o d\u00e1 bom dia e todas as promessas iniciais \u2014 a chamada proposta de valor \u2014 n\u00e3o s\u00e3o bem assim como foi dito.<\/p>\n<blockquote><p>ISSO ACONTECE PORQUE A MAIORIA DAS EMPRESAS SE IMPORTA MAIS EM VENDER, DO QUE EM SERVIR.<\/p><\/blockquote>\n<p>O que elas n\u00e3o percebem \u00e9 que essa estrat\u00e9gia sai mais caro do que deveria. Porque mesmo que voc\u00ea tenha um grande n\u00famero de novos clientes entrando todo m\u00eas, o seu funil est\u00e1 furado. Em algum momento, eles v\u00e3o embora. E, normalmente, v\u00e3o bater na porta da sua concorr\u00eancia. \u00c9 ent\u00e3o nesse momento que o empreendedor come\u00e7a a prestar aten\u00e7\u00e3o ao cen\u00e1rio, quando o churn (taxa de cancelamentos) come\u00e7a a incomodar e parece que a for\u00e7a de vendas n\u00e3o est\u00e1 trabalhando como deveria. Mas n\u00e3o se deixe enganar, talvez o desafio n\u00e3o esteja em gerar novas vendas ou em abrir novos leads, mas sim no seu relacionamento!<\/p>\n<blockquote><p>J\u00c1 PAROU PARA PENSAR QUE MUITAS\u00a0EMPRESAS T\u00caM UMA META DE VENDAS NO ANO, MAS, QUASE NENHUMA TEM UM INDICADOR DE RETEN\u00c7\u00c3O OU RETORNO DOS CLIENTES?<\/p><\/blockquote>\n<p>As empresas que s\u00e3o centradas no cliente e preocupadas genuinamente em entregar o que as pessoas pedem, gastam menos esfor\u00e7os para reter os clientes atuais \u2014 e ainda multiplicam esse n\u00famero pela indica\u00e7\u00e3o de sua marca a amigos e colegas. Seria como a rodinha de amigos do Caio que n\u00e3o muda mais a todo momento \u2014 e s\u00f3 tende a crescer.<br \/>\nNessa sele\u00e7\u00e3o, indicamos livros e ferramentas que v\u00e3o te ajudar a criar uma organiza\u00e7\u00e3o centrada no consumidor e, por consequ\u00eancia, reter os clientes atuais para obter um crescimento sustent\u00e1vel.<\/p>\n<h3>Satisfa\u00e7\u00e3o Garantida: aprenda a fazer da felicidade um bom neg\u00f3cio, por Tony Hsieh<\/h3>\n<p><a href=\"https:\/\/images.endeavor.org.br\/uploads\/2017\/08\/imagem.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-25975 size-full\" src=\"https:\/\/images.endeavor.org.br\/uploads\/2017\/08\/imagem.jpg\" alt=\"imagem\" width=\"190\" height=\"281\" \/><\/a><br \/>\nNessa empresa, o chefe paga dois mil d\u00f3lares para os candidatos desistirem do treinamento se n\u00e3o estiverem satisfeitos. Os clientes amam tanto o servi\u00e7o que decidem at\u00e9 se casar no escrit\u00f3rio. E se algu\u00e9m ligar para o SAC pedindo uma pizza, eles d\u00e3o um jeito de entregar \u2014 mesmo sendo um e-commerce de sapatos. Essa \u00e9 a Zappos, empresa idealizada por Tony Hsieh e refer\u00eancia mundial em uma cultura que coloca \u201co cliente em primeiro\u201d lugar. Nesse livro, Tony revela como conseguiu escrever essa hist\u00f3ria \u2014 e como qualquer empreendedor pode fazer o mesmo com seu neg\u00f3cio.<br \/>\n<strong>Por que ler?<\/strong><br \/>\nLivros de neg\u00f3cios costumam ser dif\u00edceis de ler do come\u00e7o ao fim, sem cansar. Mas a linguagem de Tony e as experi\u00eancias que ele compartilha s\u00e3o t\u00e3o cativantes que voc\u00ea nem vai perceber os cap\u00edtulos voarem, principalmente do meio para o fim. N\u00e3o chega a ser um manual, com passo a passo definido, mas ele consegue transmitir os porqu\u00eas e como essa cultura foi constru\u00edda do zero, o que por si s\u00f3 j\u00e1 vale a leitura.<br \/>\n<strong>Editora HarperCollins<\/strong><br \/>\n<strong>Valor:\u00a0<a href=\"http:\/\/www.buscape.com.br\/satisfacao-garantida-no-caminho-do-lucro-e-da-paixao-tony-hsieh-8578601483\" target=\"_blank\" rel=\"noopener\">A partir de R$ 23,16<\/a><\/strong><\/p>\n<h3>Nos Bastidores da Disney, por Tom Connellan<\/h3>\n<p><a href=\"https:\/\/images.endeavor.org.br\/uploads\/2017\/08\/download.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-25976 size-medium\" src=\"https:\/\/images.endeavor.org.br\/uploads\/2017\/08\/download-212x300.jpg\" alt=\"download\" width=\"212\" height=\"300\" \/><\/a><br \/>\nA Disney conseguiu. Desvendou a magia na pr\u00e1tica. At\u00e9 hoje, ela sabe como ningu\u00e9m surpreender as pessoas, tir\u00e1-las de suas vidas estressantes e ocupadas demais e conduzi-las por experi\u00eancias repletas de encantamento. Esse \u00e9 o livro que explica o neg\u00f3cio por tr\u00e1s da magia: como ela cultiva a excel\u00eancia no atendimento por meio da real aten\u00e7\u00e3o aos detalhes, de uma vis\u00e3o bem ampla do que \u00e9 a concorr\u00eancia e, acima de tudo, do empoderamento que d\u00e3o aos funcion\u00e1rios.<br \/>\n<strong>Por que ler?<\/strong><br \/>\nSua leitura \u00e9 r\u00e1pida e fluida \u2014 n\u00e3o deve durar mais do que uma viagem de avi\u00e3o. E o mais legal: leva o leitor para um passeio, junto de cinco executivos que est\u00e3o fazendo um curso no Disney Institute para entender como funciona o modelo de gest\u00e3o deles. Os aprendizados v\u00e3o se revelando por uma s\u00e9rie de exemplos que eles mesmos vivenciam e mostram ao empreendedor que l\u00ea uma rela\u00e7\u00e3o muito clara: voc\u00ea s\u00f3 ser\u00e1 capaz de gerar encantamento nos seus clientes, se antes, puder fazer isso com seus funcion\u00e1rios.<br \/>\n<strong>Editora Saraiva<\/strong><br \/>\n<strong>Valor:\u00a0<a href=\"http:\/\/www.buscape.com.br\/nos-bastidores-da-disney-22-ed-2010-tom-connellan-8502102508\" target=\"_blank\" rel=\"noopener\">A partir de R$ 24,95<\/a><\/strong><\/p>\n<h3>The Cult of the Customer: Create an Amazing Customer Experience That Turns Satisfied Customers Into Customer Evangelists, por Shep Hyken<\/h3>\n<p><a href=\"https:\/\/images.endeavor.org.br\/uploads\/2017\/08\/0470404825.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-25977 size-medium\" src=\"https:\/\/images.endeavor.org.br\/uploads\/2017\/08\/0470404825-205x300.jpg\" alt=\"9780470404829_hyken_rpt.indd\" width=\"205\" height=\"300\" \/><\/a><br \/>\nO \u201cSucesso do Cliente\u201d n\u00e3o \u00e9 um departamento, mas sim uma filosofia. E n\u00e3o precisa ser complicada, apenas eficiente. Ao longo do livro, Shep desdobra as 5 fases que s\u00e3o inerentes a uma cultura centrada no consumidor:<br \/>\nIncerteza: tenha certeza de que a experi\u00eancia \u00e9 consistentemente boa, use os indicadores certos para nunca perder isso de vista;<br \/>\nAlinhamento: simplifique a vis\u00e3o e a miss\u00e3o da sua empresa para ficar claro qual \u00e9 o \u201cjob to be done\u201d que ela entrega;<br \/>\nExperi\u00eancia: uma boa experi\u00eancia faz o cliente confiar mais em voc\u00ea e, por consequ\u00eancia, ficar;<br \/>\nCabe\u00e7a de dono: torne essas experi\u00eancias previs\u00edveis, de forma que as pessoas possam contar com voc\u00ea;<br \/>\nEncantamento: crie uma experi\u00eancia que \u00e9 consistentemente melhor que a m\u00e9dia.<br \/>\n<strong>Por que ler?<\/strong><br \/>\nOs cap\u00edtulos bem definidos te ajudam a pular para a parte que mais te interessa, caso n\u00e3o tenha tempo de ler por inteiro. Al\u00e9m disso, tem uma s\u00e9rie de hist\u00f3rias reais vividas pelo autor que materializam as boas pr\u00e1ticas que ele compartilha. Em alguns momentos, pode soar um pouco vago com frases como \u201cfa\u00e7a seus clientes amarem sua marca\u201d, mas, no geral, \u00e9 mais pr\u00e1tico e direto ao ponto. Para voc\u00ea fazer aquilo que, no fundo, j\u00e1 sabia, mas nunca tinha colocado em pr\u00e1tica.<br \/>\n<strong>Editora John Wiley &amp; Sons<\/strong><br \/>\n<strong>Valor:\u00a0<a href=\"http:\/\/www.buscape.com.br\/the-cult-of-the-customer-create-an-amazing-customer-experience-that-turns-satisfied-customers-into-customer-evangelists-shep-hyken-0470404825\" target=\"_blank\" rel=\"noopener\">A partir de R$79,90<\/a><\/strong><\/p>\n<h3>Ferramenta Job to be done: voc\u00ea est\u00e1 entregando o que seu consumidor quer?<\/h3>\n<p><a href=\"https:\/\/images.endeavor.org.br\/uploads\/2017\/08\/mockup-ipad.png\"><img decoding=\"async\" class=\"alignleft wp-image-26047 size-full\" src=\"https:\/\/images.endeavor.org.br\/uploads\/2017\/08\/mockup-ipad.png\" alt=\"mockup-ipad\" width=\"300\" height=\"200\" \/><\/a><br \/>\nNessa ferramenta, o empreendedor coloca em pr\u00e1tica os conceitos vistos nos livros acima, por\u00e9m com um olhar estrat\u00e9gico para a oferta de servi\u00e7o: se voc\u00ea quer criar uma empresa centrada no consumidor, aquilo que voc\u00ea oferece hoje \u00e9 exatamente o que ele precisa?<br \/>\n<strong>Por que usar?<\/strong><br \/>\nNesse canvas, voc\u00ea identifica as necessidades mais intr\u00ednsecas que est\u00e3o por tr\u00e1s da decis\u00e3o de compra do seu cliente e consegue us\u00e1-la para melhorar sua proposta de valor e diferencia\u00e7\u00e3o no mercado.<br \/>\n<strong><a href=\"http:\/\/info.endeavor.org.br\/ferramenta-job-to-be-done%20\" target=\"_blank\" rel=\"noopener\">Fa\u00e7a o download clicando aqui<\/a><\/strong><\/p>\n<h3>A Pergunta Definitiva 2.0, por Fred Reiccheld<\/h3>\n<p><a href=\"https:\/\/images.endeavor.org.br\/uploads\/2017\/08\/22866166.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-25978 size-medium\" src=\"https:\/\/images.endeavor.org.br\/uploads\/2017\/08\/22866166-209x300.jpg\" alt=\"22866166\" width=\"209\" height=\"300\" \/><\/a><br \/>\nCom tudo isso dito, como voc\u00ea vai saber que o seu cliente est\u00e1 mais satisfeito? A resposta \u00e9 bem simples.<br \/>\nPergunte a eles: \u201c<em>Voc\u00ea nos recomendaria um amigo<\/em>?\u201d<br \/>\nEssa pergunta resume a metodologia do NPS \u2013 Net Promoter Score, usada pelas maiores empresas do mundo \u2014 como Netflix, Apple e Microsoft. A resposta dela varia de 1 a 10, sendo que:<br \/>\nDe 0 a 6 \u2013 s\u00e3o clientes detratores, com grandes chances de n\u00e3o comprarem novamente de voc\u00ea, ou pior, de falarem mal de voc\u00ea para amigos e colegas<br \/>\nDe 7 a 8 \u2013 s\u00e3o clientes neutros, que compram de voc\u00ea, mas a qualquer momento, podem comprar de um concorrente que puder oferecer melhores condi\u00e7\u00f5es<br \/>\nDe 9 a 10 \u2013 s\u00e3o clientes promotores, que gostam muito do seu servi\u00e7o a ponto de indicarem para amigos e colegas.<br \/>\n<strong>Por que ler?<\/strong><br \/>\nA metodologia \u00e9 simples, mas o indicador \u00e9 extremamente realista. Trocando as pesquisas que levam 15 minutos para serem preenchidas por essa pergunta, o empreendedor ter\u00e1 feedbacks mais frequentes e assertivos sobre o servi\u00e7o ou produto que oferece.<br \/>\n<strong>Editora Elsevier<\/strong><br \/>\n<strong>Valor:\u00a0<a href=\"https:\/\/www.amazon.com.br\/Ultimate-Question-Revised-Expanded-Customer-Driven-ebook\/dp\/B005E8AKVM\/ref=sr_1_1?ie=UTF8&amp;qid=1502729843&amp;sr=8-1&amp;keywords=The+Ultimate+Question+2.0\" target=\"_blank\" rel=\"noopener\">A partir de R$72,90<\/a>\u00a0(vers\u00e3o em ingl\u00eas dispon\u00edvel)<\/strong><br \/>\n<strong>Fonte:\u00a0<a href=\"https:\/\/www.endeavor.org.br\/\">Endeavor<\/a>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caio sempre foi \u00f3timo em fazer novos amigos. Ele parece ser proativo, sol\u00edcito e confi\u00e1vel. O tipo de pessoa que, depois de um almo\u00e7o, voc\u00ea sente como se j\u00e1 conhecesse h\u00e1 anos. O problema \u00e9 que, logo depois de voc\u00eas ficarem amigos, ele some. Deixa para responder o WhatsApp dois dias depois, n\u00e3o atende as &hellip; <br \/><a href=\"https:\/\/vendedorautonomo.com.br\/site\/5-livros-e-ferramentas-para-colocar-o-cliente-em-primeiro-lugar\/\" class=\"more-link\">Continue lendo <span class=\"screen-reader-text\">5 livros e ferramentas para colocar o cliente em primeiro lugar<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":10910,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[502,115],"tags":[],"class_list":["post-10909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-downloads","category-vendas"],"_links":{"self":[{"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/posts\/10909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/comments?post=10909"}],"version-history":[{"count":0,"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/posts\/10909\/revisions"}],"wp:attachment":[{"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/media?parent=10909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/categories?post=10909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendedorautonomo.com.br\/site\/wp-json\/wp\/v2\/tags?post=10909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}